{"id":190897,"date":"2026-07-14T15:27:33","date_gmt":"2026-07-14T21:27:33","guid":{"rendered":"https:\/\/elotroenfoque.mx\/?p=190897"},"modified":"2026-07-14T15:27:33","modified_gmt":"2026-07-14T21:27:33","slug":"fiscal-de-guanajuato-presume-tecnologia-avanzada-para-localizacion-de-personas","status":"publish","type":"post","link":"https:\/\/elotroenfoque.mx\/index.php\/2026\/07\/14\/fiscal-de-guanajuato-presume-tecnologia-avanzada-para-localizacion-de-personas\/","title":{"rendered":"Fiscal de Guanajuato presume tecnolog\u00eda avanzada para localizaci\u00f3n de personas"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La Fiscal\u00eda General del Estado asegura que la Federaci\u00f3n y otras fiscal\u00edas del pa\u00eds buscan replicar las estrategias implementadas en Guanajuato para la localizaci\u00f3n e identificaci\u00f3n de personas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Fiscal\u00eda General del Estado de Guanajuato inform\u00f3 que los modelos de b\u00fasqueda de personas implementados desde 2025 han despertado el inter\u00e9s de la Federaci\u00f3n y de diversas fiscal\u00edas estatales, las cuales buscan conocer y replicar las estrategias desarrolladas en la entidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante una declaraci\u00f3n p\u00fablica, el fiscal se\u00f1al\u00f3 que la Fiscal\u00eda General de la Rep\u00fablica solicit\u00f3 compartir la metodolog\u00eda aplicada en Guanajuato, al considerar que los resultados obtenidos la convierten en un referente a nivel nacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Los modelos de b\u00fasqueda de Guanajuato, los que se han implementado de 2025 a la fecha, son ahora el modelo que quieren todas las fiscal\u00edas del pa\u00eds, incluida la Federaci\u00f3n&#8221;, afirm\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El funcionario atribuy\u00f3 estos avances a la inversi\u00f3n realizada en tecnolog\u00eda y al fortalecimiento de los laboratorios de gen\u00e9tica, lo que ha permitido reducir considerablemente los tiempos de identificaci\u00f3n de personas fallecidas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Explic\u00f3 que, dependiendo de las condiciones en las que sea localizado un cuerpo, actualmente es posible obtener una identificaci\u00f3n mediante pruebas de ADN en un plazo de hasta 12 horas, mientras que en otros casos el proceso puede extenderse hasta un m\u00e1ximo de 48 horas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El fiscal record\u00f3 que anteriormente exist\u00edan dudas sobre la rapidez con la que la instituci\u00f3n realizaba las identificaciones gen\u00e9ticas, incluso por parte de colectivos de b\u00fasqueda, pero asegur\u00f3 que el desarrollo tecnol\u00f3gico ha permitido alcanzar esos tiempos de respuesta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, destac\u00f3 que la Fiscal\u00eda mantiene campa\u00f1as permanentes para la toma de muestras de ADN, adem\u00e1s de operar c\u00e9lulas de b\u00fasqueda y programas de entrega digna de cuerpos a sus familiares.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n lee:\u00a0<strong><a href=\"https:\/\/elotroenfoque.mx\/index.php\/2026\/07\/13\/sep-anuncia-cambio-para-el-proximo-ciclo-escolar-cual-es\/\">SEP anuncia cambio para el pr\u00f3ximo ciclo escolar, \u00bfcu\u00e1l es?<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente, indic\u00f3 que estas acciones forman parte de las estrategias que ser\u00e1n presentadas ante la Conferencia Nacional de Fiscales, luego de que la Fiscal\u00eda General de la Rep\u00fablica solicitara exponer el modelo de trabajo desarrollado en Guanajuato como una pr\u00e1ctica de referencia para otras entidades del pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/www.tiktok.com\/@elotroenfoque?_r=1&amp;_t=ZS-97ffhW6kR1t\">Sigue tambi\u00e9n las noticias en TikTok<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Fiscal\u00eda General del Estado asegura que la Federaci\u00f3n y otras fiscal\u00edas del pa\u00eds buscan replicar las estrategias implementadas en Guanajuato para la localizaci\u00f3n e identificaci\u00f3n de personas. La Fiscal\u00eda General del Estado de Guanajuato inform\u00f3 que los modelos de b\u00fasqueda de personas implementados desde 2025 han despertado el inter\u00e9s de la Federaci\u00f3n y de&#8230;<\/p>\n","protected":false},"author":4,"featured_media":182005,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[13,4517],"class_list":["post-190897","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-guanajuato","tag-noticias-guanajuato"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fiscal de Guanajuato presume tecnolog\u00eda avanzada para localizaci\u00f3n de personas - El otro enfoque<\/title>\n<meta name=\"description\" content=\"La Fiscal\u00eda de Guanajuato asegur\u00f3 que su modelo de b\u00fasqueda de personas e identificaci\u00f3n por ADN es referente nacional.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elotroenfoque.mx\/index.php\/2026\/07\/14\/fiscal-de-guanajuato-presume-tecnologia-avanzada-para-localizacion-de-personas\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiscal de Guanajuato presume tecnolog\u00eda avanzada para localizaci\u00f3n de personas - El otro enfoque\" \/>\n<meta property=\"og:description\" content=\"La Fiscal\u00eda de Guanajuato asegur\u00f3 que su modelo de b\u00fasqueda de personas e identificaci\u00f3n por ADN es referente nacional.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elotroenfoque.mx\/index.php\/2026\/07\/14\/fiscal-de-guanajuato-presume-tecnologia-avanzada-para-localizacion-de-personas\/\" \/>\n<meta property=\"og:site_name\" content=\"El otro enfoque\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-14T21:27:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elotroenfoque.mx\/wp-content\/uploads\/2026\/03\/fiscal-gerardo-vazquez-alatriste.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"766\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redaccion\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redaccion\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/elotroenfoque.mx\\\/index.php\\\/2026\\\/07\\\/14\\\/fiscal-de-guanajuato-presume-tecnologia-avanzada-para-localizacion-de-personas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elotroenfoque.mx\\\/index.php\\\/2026\\\/07\\\/14\\\/fiscal-de-guanajuato-presume-tecnologia-avanzada-para-localizacion-de-personas\\\/\"},\"author\":{\"name\":\"Redaccion\",\"@id\":\"https:\\\/\\\/elotroenfoque.mx\\\/#\\\/schema\\\/person\\\/8eb322f84d0bd9f337e462905519a1ae\"},\"headline\":\"Fiscal de Guanajuato presume tecnolog\u00eda avanzada para localizaci\u00f3n de personas\",\"datePublished\":\"2026-07-14T21:27:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/elotroenfoque.mx\\\/index.php\\\/2026\\\/07\\\/14\\\/fiscal-de-guanajuato-presume-tecnologia-avanzada-para-localizacion-de-personas\\\/\"},\"wordCount\":402,\"image\":{\"@id\":\"https:\\\/\\\/elotroenfoque.mx\\\/index.php\\\/2026\\\/07\\\/14\\\/fiscal-de-guanajuato-presume-tecnologia-avanzada-para-localizacion-de-personas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/elotroenfoque.mx\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/fiscal-gerardo-vazquez-alatriste.jpeg\",\"keywords\":[\"Guanajuato\",\"Noticias Guanajuato\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/elotroenfoque.mx\\\/index.php\\\/2026\\\/07\\\/14\\\/fiscal-de-guanajuato-presume-tecnologia-avanzada-para-localizacion-de-personas\\\/\",\"url\":\"https:\\\/\\\/elotroenfoque.mx\\\/index.php\\\/2026\\\/07\\\/14\\\/fiscal-de-guanajuato-presume-tecnologia-avanzada-para-localizacion-de-personas\\\/\",\"name\":\"Fiscal de Guanajuato presume tecnolog\u00eda avanzada para localizaci\u00f3n de personas - El otro enfoque\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elotroenfoque.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/elotroenfoque.mx\\\/index.php\\\/2026\\\/07\\\/14\\\/fiscal-de-guanajuato-presume-tecnologia-avanzada-para-localizacion-de-personas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/elotroenfoque.mx\\\/index.php\\\/2026\\\/07\\\/14\\\/fiscal-de-guanajuato-presume-tecnologia-avanzada-para-localizacion-de-personas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/elotroenfoque.mx\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/fiscal-gerardo-vazquez-alatriste.jpeg\",\"datePublished\":\"2026-07-14T21:27:33+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/elotroenfoque.mx\\\/#\\\/schema\\\/person\\\/8eb322f84d0bd9f337e462905519a1ae\"},\"description\":\"La Fiscal\u00eda de Guanajuato asegur\u00f3 que su modelo de b\u00fasqueda de personas e identificaci\u00f3n por ADN es referente nacional.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/elotroenfoque.mx\\\/index.php\\\/2026\\\/07\\\/14\\\/fiscal-de-guanajuato-presume-tecnologia-avanzada-para-localizacion-de-personas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/elotroenfoque.mx\\\/index.php\\\/2026\\\/07\\\/14\\\/fiscal-de-guanajuato-presume-tecnologia-avanzada-para-localizacion-de-personas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/elotroenfoque.mx\\\/index.php\\\/2026\\\/07\\\/14\\\/fiscal-de-guanajuato-presume-tecnologia-avanzada-para-localizacion-de-personas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/elotroenfoque.mx\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/fiscal-gerardo-vazquez-alatriste.jpeg\",\"contentUrl\":\"https:\\\/\\\/elotroenfoque.mx\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/fiscal-gerardo-vazquez-alatriste.jpeg\",\"width\":1280,\"height\":766,\"caption\":\"Presume tecnolog\u00eda para localizaci\u00f3n de personas\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/elotroenfoque.mx\\\/index.php\\\/2026\\\/07\\\/14\\\/fiscal-de-guanajuato-presume-tecnologia-avanzada-para-localizacion-de-personas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/elotroenfoque.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fiscal de Guanajuato presume tecnolog\u00eda avanzada para localizaci\u00f3n de personas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/elotroenfoque.mx\\\/#website\",\"url\":\"https:\\\/\\\/elotroenfoque.mx\\\/\",\"name\":\"El otro enfoque\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/elotroenfoque.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/elotroenfoque.mx\\\/#\\\/schema\\\/person\\\/8eb322f84d0bd9f337e462905519a1ae\",\"name\":\"Redaccion\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3579478e2b4e7aad364a32b26cf744b360ae0e581ee1cd0cb18a8f239ee49ac4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3579478e2b4e7aad364a32b26cf744b360ae0e581ee1cd0cb18a8f239ee49ac4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3579478e2b4e7aad364a32b26cf744b360ae0e581ee1cd0cb18a8f239ee49ac4?s=96&d=mm&r=g\",\"caption\":\"Redaccion\"},\"url\":\"https:\\\/\\\/elotroenfoque.mx\\\/index.php\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiscal de Guanajuato presume tecnolog\u00eda avanzada para localizaci\u00f3n de personas - El otro enfoque","description":"La Fiscal\u00eda de Guanajuato asegur\u00f3 que su modelo de b\u00fasqueda de personas e identificaci\u00f3n por ADN es referente nacional.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elotroenfoque.mx\/index.php\/2026\/07\/14\/fiscal-de-guanajuato-presume-tecnologia-avanzada-para-localizacion-de-personas\/","og_locale":"es_MX","og_type":"article","og_title":"Fiscal de Guanajuato presume tecnolog\u00eda avanzada para localizaci\u00f3n de personas - El otro enfoque","og_description":"La Fiscal\u00eda de Guanajuato asegur\u00f3 que su modelo de b\u00fasqueda de personas e identificaci\u00f3n por ADN es referente nacional.","og_url":"https:\/\/elotroenfoque.mx\/index.php\/2026\/07\/14\/fiscal-de-guanajuato-presume-tecnologia-avanzada-para-localizacion-de-personas\/","og_site_name":"El otro enfoque","article_published_time":"2026-07-14T21:27:33+00:00","og_image":[{"width":1280,"height":766,"url":"https:\/\/elotroenfoque.mx\/wp-content\/uploads\/2026\/03\/fiscal-gerardo-vazquez-alatriste.jpeg","type":"image\/jpeg"}],"author":"Redaccion","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Redaccion","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/elotroenfoque.mx\/index.php\/2026\/07\/14\/fiscal-de-guanajuato-presume-tecnologia-avanzada-para-localizacion-de-personas\/#article","isPartOf":{"@id":"https:\/\/elotroenfoque.mx\/index.php\/2026\/07\/14\/fiscal-de-guanajuato-presume-tecnologia-avanzada-para-localizacion-de-personas\/"},"author":{"name":"Redaccion","@id":"https:\/\/elotroenfoque.mx\/#\/schema\/person\/8eb322f84d0bd9f337e462905519a1ae"},"headline":"Fiscal de Guanajuato presume tecnolog\u00eda avanzada para localizaci\u00f3n de personas","datePublished":"2026-07-14T21:27:33+00:00","mainEntityOfPage":{"@id":"https:\/\/elotroenfoque.mx\/index.php\/2026\/07\/14\/fiscal-de-guanajuato-presume-tecnologia-avanzada-para-localizacion-de-personas\/"},"wordCount":402,"image":{"@id":"https:\/\/elotroenfoque.mx\/index.php\/2026\/07\/14\/fiscal-de-guanajuato-presume-tecnologia-avanzada-para-localizacion-de-personas\/#primaryimage"},"thumbnailUrl":"https:\/\/elotroenfoque.mx\/wp-content\/uploads\/2026\/03\/fiscal-gerardo-vazquez-alatriste.jpeg","keywords":["Guanajuato","Noticias Guanajuato"],"articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/elotroenfoque.mx\/index.php\/2026\/07\/14\/fiscal-de-guanajuato-presume-tecnologia-avanzada-para-localizacion-de-personas\/","url":"https:\/\/elotroenfoque.mx\/index.php\/2026\/07\/14\/fiscal-de-guanajuato-presume-tecnologia-avanzada-para-localizacion-de-personas\/","name":"Fiscal de Guanajuato presume tecnolog\u00eda avanzada para localizaci\u00f3n de personas - El otro enfoque","isPartOf":{"@id":"https:\/\/elotroenfoque.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/elotroenfoque.mx\/index.php\/2026\/07\/14\/fiscal-de-guanajuato-presume-tecnologia-avanzada-para-localizacion-de-personas\/#primaryimage"},"image":{"@id":"https:\/\/elotroenfoque.mx\/index.php\/2026\/07\/14\/fiscal-de-guanajuato-presume-tecnologia-avanzada-para-localizacion-de-personas\/#primaryimage"},"thumbnailUrl":"https:\/\/elotroenfoque.mx\/wp-content\/uploads\/2026\/03\/fiscal-gerardo-vazquez-alatriste.jpeg","datePublished":"2026-07-14T21:27:33+00:00","author":{"@id":"https:\/\/elotroenfoque.mx\/#\/schema\/person\/8eb322f84d0bd9f337e462905519a1ae"},"description":"La Fiscal\u00eda de Guanajuato asegur\u00f3 que su modelo de b\u00fasqueda de personas e identificaci\u00f3n por ADN es referente nacional.","breadcrumb":{"@id":"https:\/\/elotroenfoque.mx\/index.php\/2026\/07\/14\/fiscal-de-guanajuato-presume-tecnologia-avanzada-para-localizacion-de-personas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elotroenfoque.mx\/index.php\/2026\/07\/14\/fiscal-de-guanajuato-presume-tecnologia-avanzada-para-localizacion-de-personas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elotroenfoque.mx\/index.php\/2026\/07\/14\/fiscal-de-guanajuato-presume-tecnologia-avanzada-para-localizacion-de-personas\/#primaryimage","url":"https:\/\/elotroenfoque.mx\/wp-content\/uploads\/2026\/03\/fiscal-gerardo-vazquez-alatriste.jpeg","contentUrl":"https:\/\/elotroenfoque.mx\/wp-content\/uploads\/2026\/03\/fiscal-gerardo-vazquez-alatriste.jpeg","width":1280,"height":766,"caption":"Presume tecnolog\u00eda para localizaci\u00f3n de personas"},{"@type":"BreadcrumbList","@id":"https:\/\/elotroenfoque.mx\/index.php\/2026\/07\/14\/fiscal-de-guanajuato-presume-tecnologia-avanzada-para-localizacion-de-personas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/elotroenfoque.mx\/"},{"@type":"ListItem","position":2,"name":"Fiscal de Guanajuato presume tecnolog\u00eda avanzada para localizaci\u00f3n de personas"}]},{"@type":"WebSite","@id":"https:\/\/elotroenfoque.mx\/#website","url":"https:\/\/elotroenfoque.mx\/","name":"El otro enfoque","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elotroenfoque.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/elotroenfoque.mx\/#\/schema\/person\/8eb322f84d0bd9f337e462905519a1ae","name":"Redaccion","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/3579478e2b4e7aad364a32b26cf744b360ae0e581ee1cd0cb18a8f239ee49ac4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3579478e2b4e7aad364a32b26cf744b360ae0e581ee1cd0cb18a8f239ee49ac4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3579478e2b4e7aad364a32b26cf744b360ae0e581ee1cd0cb18a8f239ee49ac4?s=96&d=mm&r=g","caption":"Redaccion"},"url":"https:\/\/elotroenfoque.mx\/index.php\/author\/redaccion\/"}]}},"_links":{"self":[{"href":"https:\/\/elotroenfoque.mx\/index.php\/wp-json\/wp\/v2\/posts\/190897","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elotroenfoque.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elotroenfoque.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elotroenfoque.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/elotroenfoque.mx\/index.php\/wp-json\/wp\/v2\/comments?post=190897"}],"version-history":[{"count":2,"href":"https:\/\/elotroenfoque.mx\/index.php\/wp-json\/wp\/v2\/posts\/190897\/revisions"}],"predecessor-version":[{"id":190902,"href":"https:\/\/elotroenfoque.mx\/index.php\/wp-json\/wp\/v2\/posts\/190897\/revisions\/190902"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elotroenfoque.mx\/index.php\/wp-json\/wp\/v2\/media\/182005"}],"wp:attachment":[{"href":"https:\/\/elotroenfoque.mx\/index.php\/wp-json\/wp\/v2\/media?parent=190897"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elotroenfoque.mx\/index.php\/wp-json\/wp\/v2\/categories?post=190897"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elotroenfoque.mx\/index.php\/wp-json\/wp\/v2\/tags?post=190897"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}