{"id":195413,"date":"2026-09-02T14:10:14","date_gmt":"2026-09-02T20:10:14","guid":{"rendered":"https:\/\/elotroenfoque.mx\/?p=195413"},"modified":"2026-09-02T14:10:15","modified_gmt":"2026-09-02T20:10:15","slug":"irapuatense-halla-chamba-en-redes-sociales-en-jalisco-va-y-desaparece","status":"publish","type":"post","link":"https:\/\/elotroenfoque.mx\/index.php\/2026\/09\/02\/irapuatense-halla-chamba-en-redes-sociales-en-jalisco-va-y-desaparece\/","title":{"rendered":"Irapuatense halla \u201cchamba\u201d en redes sociales en Jalisco, va y desaparece"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Lo que parec\u00eda ser una oportunidad para conseguir trabajo termin\u00f3 convirti\u00e9ndose en una angustia para una familia de Irapuato. Jos\u00e9 Manuel Guti\u00e9rrez Barrera viaj\u00f3 a Guadalajara, Jalisco, despu\u00e9s de aceptar una oferta laboral que recibi\u00f3 a trav\u00e9s de redes sociales, pero desde entonces sus familiares perdieron toda comunicaci\u00f3n con \u00e9l.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jos\u00e9 Manuel sali\u00f3 de su domicilio el viernes 28 de agosto, con la intenci\u00f3n de trasladarse a Guadalajara para comenzar, aparentemente, una nueva oportunidad de trabajo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"972\" height=\"973\" src=\"https:\/\/elotroenfoque.mx\/wp-content\/uploads\/2026\/09\/ee.jpg\" alt=\"\" class=\"wp-image-195415\" srcset=\"https:\/\/elotroenfoque.mx\/wp-content\/uploads\/2026\/09\/ee.jpg 972w, https:\/\/elotroenfoque.mx\/wp-content\/uploads\/2026\/09\/ee-150x150.jpg 150w, https:\/\/elotroenfoque.mx\/wp-content\/uploads\/2026\/09\/ee-300x300.jpg 300w, https:\/\/elotroenfoque.mx\/wp-content\/uploads\/2026\/09\/ee-767x768.jpg 767w\" sizes=\"auto, (max-width: 972px) 100vw, 972px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con la informaci\u00f3n difundida en Facebook por el colectivo de b\u00fasqueda Hasta Encontrarte, el joven inform\u00f3 a sus familiares que llegar\u00eda a la Central Nueva de Guadalajara, lugar donde se reunir\u00eda con la persona o personas que le hab\u00edan ofrecido el empleo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, despu\u00e9s de su llegada, la comunicaci\u00f3n se perdi\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Su familia teme por su seguridad<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ante la falta de noticias, sus familiares acudieron ante el Ministerio P\u00fablico de la Fiscal\u00eda del Estado para presentar una denuncia y solicitar la b\u00fasqueda de Jos\u00e9 Manuel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La preocupaci\u00f3n aument\u00f3 al no poder establecer contacto con \u00e9l y desconocer su ubicaci\u00f3n actual.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El colectivo Hasta Encontrarte difundi\u00f3 en su p\u00e1gina oficial de Facebook tres fotograf\u00edas del joven, con el objetivo de que puedan ser identificadas por personas que lo hayan visto o tengan informaci\u00f3n sobre su posible paradero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Piden compartir cualquier informaci\u00f3n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El colectivo hizo un llamado a la ciudadan\u00eda para colaborar con la b\u00fasqueda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cualquier dato que pueda ayudar a localizar a Jos\u00e9 Manuel Guti\u00e9rrez Barrera puede ser enviado mediante mensaje privado a la p\u00e1gina de Facebook de Hasta Encontrarte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El grupo reiter\u00f3 su postura frente a los casos de desaparici\u00f3n con los mensajes:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cA los desaparecidos no se les juzga, se les busca\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y: \u201cNo buscamos culpables, solo que regresen a casa\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Preocupan las ofertas de trabajo difundidas en redes<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La desaparici\u00f3n tambi\u00e9n gener\u00f3 comentarios entre usuarios de redes sociales, quienes expresaron preocupaci\u00f3n por las ofertas laborales que circulan por internet y que implican trasladarse a otros estados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras tanto, la familia de Jos\u00e9 Manuel espera que cualquier informaci\u00f3n pueda ayudar a establecer d\u00f3nde se encuentra y permitir que regrese a casa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/elotroenfoque.mx\/index.php\/2026\/09\/02\/cae-en-leon-banda-dedicada-al-robo-de-traileres\/\">Cae banda de ladrones de tr\u00e1ileres en Le\u00f3n<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si tienes informaci\u00f3n que pueda contribuir a localizarlo, puedes comunicarte mediante mensaje privado con el colectivo Hasta Encontrarte o con autoridades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/www.tiktok.com\/@elotroenfoque?_r=1&amp;_t=ZS-97ffhW6kR1t\">Sigue tambi\u00e9n las noticias en TikTok<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lo que parec\u00eda ser una oportunidad para conseguir trabajo termin\u00f3 convirti\u00e9ndose en una angustia para una familia de Irapuato. Jos\u00e9 Manuel Guti\u00e9rrez Barrera viaj\u00f3 a Guadalajara, Jalisco, despu\u00e9s de aceptar una oferta laboral que recibi\u00f3 a trav\u00e9s de redes sociales, pero desde entonces sus familiares perdieron toda comunicaci\u00f3n con \u00e9l. Jos\u00e9 Manuel sali\u00f3 de su&#8230;<\/p>\n","protected":false},"author":4,"featured_media":195414,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[13,4517],"class_list":["post-195413","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-guanajuato","tag-noticias-guanajuato"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Irapuatense halla \u201cchamba\u201d en redes sociales en Jalisco, va y desaparece - El otro enfoque<\/title>\n<meta name=\"description\" content=\"os\u00e9 Manuel Guti\u00e9rrez Barrera, joven de Irapuato, desapareci\u00f3 tras viajar a Guadalajara por una oferta laboral recibida en redes sociales\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elotroenfoque.mx\/index.php\/2026\/09\/02\/irapuatense-halla-chamba-en-redes-sociales-en-jalisco-va-y-desaparece\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Irapuatense halla \u201cchamba\u201d en redes sociales en Jalisco, va y desaparece - El otro enfoque\" \/>\n<meta property=\"og:description\" content=\"os\u00e9 Manuel Guti\u00e9rrez Barrera, joven de Irapuato, desapareci\u00f3 tras viajar a Guadalajara por una oferta laboral recibida en redes sociales\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elotroenfoque.mx\/index.php\/2026\/09\/02\/irapuatense-halla-chamba-en-redes-sociales-en-jalisco-va-y-desaparece\/\" \/>\n<meta property=\"og:site_name\" content=\"El otro enfoque\" \/>\n<meta property=\"article:published_time\" content=\"2026-09-02T20:10:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-02T20:10:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elotroenfoque.mx\/wp-content\/uploads\/2026\/09\/e.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"997\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Equipo Redaccion\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipo Redaccion\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/elotroenfoque.mx\\\/index.php\\\/2026\\\/09\\\/02\\\/irapuatense-halla-chamba-en-redes-sociales-en-jalisco-va-y-desaparece\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elotroenfoque.mx\\\/index.php\\\/2026\\\/09\\\/02\\\/irapuatense-halla-chamba-en-redes-sociales-en-jalisco-va-y-desaparece\\\/\"},\"author\":{\"name\":\"Equipo Redaccion\",\"@id\":\"https:\\\/\\\/elotroenfoque.mx\\\/#\\\/schema\\\/person\\\/8eb322f84d0bd9f337e462905519a1ae\"},\"headline\":\"Irapuatense halla \u201cchamba\u201d en redes sociales en Jalisco, va y desaparece\",\"datePublished\":\"2026-09-02T20:10:14+00:00\",\"dateModified\":\"2026-09-02T20:10:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/elotroenfoque.mx\\\/index.php\\\/2026\\\/09\\\/02\\\/irapuatense-halla-chamba-en-redes-sociales-en-jalisco-va-y-desaparece\\\/\"},\"wordCount\":433,\"image\":{\"@id\":\"https:\\\/\\\/elotroenfoque.mx\\\/index.php\\\/2026\\\/09\\\/02\\\/irapuatense-halla-chamba-en-redes-sociales-en-jalisco-va-y-desaparece\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/elotroenfoque.mx\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/e.jpg\",\"keywords\":[\"Guanajuato\",\"Noticias Guanajuato\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/elotroenfoque.mx\\\/index.php\\\/2026\\\/09\\\/02\\\/irapuatense-halla-chamba-en-redes-sociales-en-jalisco-va-y-desaparece\\\/\",\"url\":\"https:\\\/\\\/elotroenfoque.mx\\\/index.php\\\/2026\\\/09\\\/02\\\/irapuatense-halla-chamba-en-redes-sociales-en-jalisco-va-y-desaparece\\\/\",\"name\":\"Irapuatense halla \u201cchamba\u201d en redes sociales en Jalisco, va y desaparece - El otro enfoque\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elotroenfoque.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/elotroenfoque.mx\\\/index.php\\\/2026\\\/09\\\/02\\\/irapuatense-halla-chamba-en-redes-sociales-en-jalisco-va-y-desaparece\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/elotroenfoque.mx\\\/index.php\\\/2026\\\/09\\\/02\\\/irapuatense-halla-chamba-en-redes-sociales-en-jalisco-va-y-desaparece\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/elotroenfoque.mx\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/e.jpg\",\"datePublished\":\"2026-09-02T20:10:14+00:00\",\"dateModified\":\"2026-09-02T20:10:15+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/elotroenfoque.mx\\\/#\\\/schema\\\/person\\\/8eb322f84d0bd9f337e462905519a1ae\"},\"description\":\"os\u00e9 Manuel Guti\u00e9rrez Barrera, joven de Irapuato, desapareci\u00f3 tras viajar a Guadalajara por una oferta laboral recibida en redes sociales\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/elotroenfoque.mx\\\/index.php\\\/2026\\\/09\\\/02\\\/irapuatense-halla-chamba-en-redes-sociales-en-jalisco-va-y-desaparece\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/elotroenfoque.mx\\\/index.php\\\/2026\\\/09\\\/02\\\/irapuatense-halla-chamba-en-redes-sociales-en-jalisco-va-y-desaparece\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/elotroenfoque.mx\\\/index.php\\\/2026\\\/09\\\/02\\\/irapuatense-halla-chamba-en-redes-sociales-en-jalisco-va-y-desaparece\\\/#primaryimage\",\"url\":\"https:\\\/\\\/elotroenfoque.mx\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/e.jpg\",\"contentUrl\":\"https:\\\/\\\/elotroenfoque.mx\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/e.jpg\",\"width\":1080,\"height\":997,\"caption\":\"Irapuatense desaparece en Jalisco\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/elotroenfoque.mx\\\/index.php\\\/2026\\\/09\\\/02\\\/irapuatense-halla-chamba-en-redes-sociales-en-jalisco-va-y-desaparece\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/elotroenfoque.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Irapuatense halla \u201cchamba\u201d en redes sociales en Jalisco, va y desaparece\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/elotroenfoque.mx\\\/#website\",\"url\":\"https:\\\/\\\/elotroenfoque.mx\\\/\",\"name\":\"El otro enfoque\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/elotroenfoque.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/elotroenfoque.mx\\\/#\\\/schema\\\/person\\\/8eb322f84d0bd9f337e462905519a1ae\",\"name\":\"Equipo Redaccion\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3579478e2b4e7aad364a32b26cf744b360ae0e581ee1cd0cb18a8f239ee49ac4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3579478e2b4e7aad364a32b26cf744b360ae0e581ee1cd0cb18a8f239ee49ac4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3579478e2b4e7aad364a32b26cf744b360ae0e581ee1cd0cb18a8f239ee49ac4?s=96&d=mm&r=g\",\"caption\":\"Equipo Redaccion\"},\"url\":\"https:\\\/\\\/elotroenfoque.mx\\\/index.php\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Irapuatense halla \u201cchamba\u201d en redes sociales en Jalisco, va y desaparece - El otro enfoque","description":"os\u00e9 Manuel Guti\u00e9rrez Barrera, joven de Irapuato, desapareci\u00f3 tras viajar a Guadalajara por una oferta laboral recibida en redes sociales","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elotroenfoque.mx\/index.php\/2026\/09\/02\/irapuatense-halla-chamba-en-redes-sociales-en-jalisco-va-y-desaparece\/","og_locale":"es_MX","og_type":"article","og_title":"Irapuatense halla \u201cchamba\u201d en redes sociales en Jalisco, va y desaparece - El otro enfoque","og_description":"os\u00e9 Manuel Guti\u00e9rrez Barrera, joven de Irapuato, desapareci\u00f3 tras viajar a Guadalajara por una oferta laboral recibida en redes sociales","og_url":"https:\/\/elotroenfoque.mx\/index.php\/2026\/09\/02\/irapuatense-halla-chamba-en-redes-sociales-en-jalisco-va-y-desaparece\/","og_site_name":"El otro enfoque","article_published_time":"2026-09-02T20:10:14+00:00","article_modified_time":"2026-09-02T20:10:15+00:00","og_image":[{"width":1080,"height":997,"url":"https:\/\/elotroenfoque.mx\/wp-content\/uploads\/2026\/09\/e.jpg","type":"image\/jpeg"}],"author":"Equipo Redaccion","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Equipo Redaccion","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/elotroenfoque.mx\/index.php\/2026\/09\/02\/irapuatense-halla-chamba-en-redes-sociales-en-jalisco-va-y-desaparece\/#article","isPartOf":{"@id":"https:\/\/elotroenfoque.mx\/index.php\/2026\/09\/02\/irapuatense-halla-chamba-en-redes-sociales-en-jalisco-va-y-desaparece\/"},"author":{"name":"Equipo Redaccion","@id":"https:\/\/elotroenfoque.mx\/#\/schema\/person\/8eb322f84d0bd9f337e462905519a1ae"},"headline":"Irapuatense halla \u201cchamba\u201d en redes sociales en Jalisco, va y desaparece","datePublished":"2026-09-02T20:10:14+00:00","dateModified":"2026-09-02T20:10:15+00:00","mainEntityOfPage":{"@id":"https:\/\/elotroenfoque.mx\/index.php\/2026\/09\/02\/irapuatense-halla-chamba-en-redes-sociales-en-jalisco-va-y-desaparece\/"},"wordCount":433,"image":{"@id":"https:\/\/elotroenfoque.mx\/index.php\/2026\/09\/02\/irapuatense-halla-chamba-en-redes-sociales-en-jalisco-va-y-desaparece\/#primaryimage"},"thumbnailUrl":"https:\/\/elotroenfoque.mx\/wp-content\/uploads\/2026\/09\/e.jpg","keywords":["Guanajuato","Noticias Guanajuato"],"articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/elotroenfoque.mx\/index.php\/2026\/09\/02\/irapuatense-halla-chamba-en-redes-sociales-en-jalisco-va-y-desaparece\/","url":"https:\/\/elotroenfoque.mx\/index.php\/2026\/09\/02\/irapuatense-halla-chamba-en-redes-sociales-en-jalisco-va-y-desaparece\/","name":"Irapuatense halla \u201cchamba\u201d en redes sociales en Jalisco, va y desaparece - El otro enfoque","isPartOf":{"@id":"https:\/\/elotroenfoque.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/elotroenfoque.mx\/index.php\/2026\/09\/02\/irapuatense-halla-chamba-en-redes-sociales-en-jalisco-va-y-desaparece\/#primaryimage"},"image":{"@id":"https:\/\/elotroenfoque.mx\/index.php\/2026\/09\/02\/irapuatense-halla-chamba-en-redes-sociales-en-jalisco-va-y-desaparece\/#primaryimage"},"thumbnailUrl":"https:\/\/elotroenfoque.mx\/wp-content\/uploads\/2026\/09\/e.jpg","datePublished":"2026-09-02T20:10:14+00:00","dateModified":"2026-09-02T20:10:15+00:00","author":{"@id":"https:\/\/elotroenfoque.mx\/#\/schema\/person\/8eb322f84d0bd9f337e462905519a1ae"},"description":"os\u00e9 Manuel Guti\u00e9rrez Barrera, joven de Irapuato, desapareci\u00f3 tras viajar a Guadalajara por una oferta laboral recibida en redes sociales","breadcrumb":{"@id":"https:\/\/elotroenfoque.mx\/index.php\/2026\/09\/02\/irapuatense-halla-chamba-en-redes-sociales-en-jalisco-va-y-desaparece\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elotroenfoque.mx\/index.php\/2026\/09\/02\/irapuatense-halla-chamba-en-redes-sociales-en-jalisco-va-y-desaparece\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elotroenfoque.mx\/index.php\/2026\/09\/02\/irapuatense-halla-chamba-en-redes-sociales-en-jalisco-va-y-desaparece\/#primaryimage","url":"https:\/\/elotroenfoque.mx\/wp-content\/uploads\/2026\/09\/e.jpg","contentUrl":"https:\/\/elotroenfoque.mx\/wp-content\/uploads\/2026\/09\/e.jpg","width":1080,"height":997,"caption":"Irapuatense desaparece en Jalisco"},{"@type":"BreadcrumbList","@id":"https:\/\/elotroenfoque.mx\/index.php\/2026\/09\/02\/irapuatense-halla-chamba-en-redes-sociales-en-jalisco-va-y-desaparece\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/elotroenfoque.mx\/"},{"@type":"ListItem","position":2,"name":"Irapuatense halla \u201cchamba\u201d en redes sociales en Jalisco, va y desaparece"}]},{"@type":"WebSite","@id":"https:\/\/elotroenfoque.mx\/#website","url":"https:\/\/elotroenfoque.mx\/","name":"El otro enfoque","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elotroenfoque.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/elotroenfoque.mx\/#\/schema\/person\/8eb322f84d0bd9f337e462905519a1ae","name":"Equipo Redaccion","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/3579478e2b4e7aad364a32b26cf744b360ae0e581ee1cd0cb18a8f239ee49ac4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3579478e2b4e7aad364a32b26cf744b360ae0e581ee1cd0cb18a8f239ee49ac4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3579478e2b4e7aad364a32b26cf744b360ae0e581ee1cd0cb18a8f239ee49ac4?s=96&d=mm&r=g","caption":"Equipo Redaccion"},"url":"https:\/\/elotroenfoque.mx\/index.php\/author\/redaccion\/"}]}},"_links":{"self":[{"href":"https:\/\/elotroenfoque.mx\/index.php\/wp-json\/wp\/v2\/posts\/195413","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elotroenfoque.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elotroenfoque.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elotroenfoque.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/elotroenfoque.mx\/index.php\/wp-json\/wp\/v2\/comments?post=195413"}],"version-history":[{"count":1,"href":"https:\/\/elotroenfoque.mx\/index.php\/wp-json\/wp\/v2\/posts\/195413\/revisions"}],"predecessor-version":[{"id":195416,"href":"https:\/\/elotroenfoque.mx\/index.php\/wp-json\/wp\/v2\/posts\/195413\/revisions\/195416"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elotroenfoque.mx\/index.php\/wp-json\/wp\/v2\/media\/195414"}],"wp:attachment":[{"href":"https:\/\/elotroenfoque.mx\/index.php\/wp-json\/wp\/v2\/media?parent=195413"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elotroenfoque.mx\/index.php\/wp-json\/wp\/v2\/categories?post=195413"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elotroenfoque.mx\/index.php\/wp-json\/wp\/v2\/tags?post=195413"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}